{"id":39835,"date":"2025-06-29T13:16:52","date_gmt":"2025-06-29T11:16:52","guid":{"rendered":"https:\/\/www.jojoenherbe.com\/?p=39835"},"modified":"2025-07-13T10:07:57","modified_gmt":"2025-07-13T08:07:57","slug":"point-lecture-hebdomadaire-2025-25","status":"publish","type":"post","link":"https:\/\/www.jojoenherbe.com\/index.php\/2025\/06\/29\/point-lecture-hebdomadaire-2025-25\/","title":{"rendered":"Point lecture hebdomadaire 2025 #25"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>En cette fin de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re qui ont \u00e9t\u00e9 peu nombreuses, compte-tenu de nos sorties du soir (plage, f\u00eate de la musique&#8230;) ou visionnages.\u00a0<\/em><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Nos lectures du 16 au 22 juin 2025<\/span>:<\/strong><\/p>\n<p><em><span style=\"text-decoration: underline;\">Des lectures jeunesse<\/span>:<\/em><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-legende-de-Podkin-le-Brave-T2-et-T3-scaled.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"39920\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2025\/06\/29\/point-lecture-hebdomadaire-2025-25\/la-legende-de-podkin-le-brave-t2-et-t3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-legende-de-Podkin-le-Brave-T2-et-T3-scaled.jpg?fit=2560%2C1841&amp;ssl=1\" data-orig-size=\"2560,1841\" data-comments-opened=\"1\" data-image-title=\"La l\u00e9gende de Podkin le Brave T2 et T3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-legende-de-Podkin-le-Brave-T2-et-T3-scaled.jpg?fit=676%2C486&amp;ssl=1\" class=\"alignleft size-thumbnail wp-image-39920\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-legende-de-Podkin-le-Brave-T2-et-T3.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-legende-de-Podkin-le-Brave-T2-et-T3-scaled.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-legende-de-Podkin-le-Brave-T2-et-T3-scaled.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-legende-de-Podkin-le-Brave-T2-et-T3-scaled.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Nous avons fini les derniers chapitres du tome 2 de <span style=\"text-decoration: underline;\"><strong>La l\u00e9gende de Podkin le Brave<\/strong>, <strong>Le tr\u00e9sor du terrier maudit<\/strong><\/span> de Kieran Larwood (\u00e9d. Gallimard Jeunesse, coll. Folio Junior, octobre 2020, 304 pages) et avons encha\u00een\u00e9, d\u00e8s le lendemain soir, avec le troisi\u00e8me et dernier tome, <strong><span style=\"text-decoration: underline;\">Le Monstre de C\u0153ur Sombre<\/span><\/strong> (juin 2021, 304 pages). Nous suivons toujours les aventures des trois lapereaux &#8211; Podkin, Paz et Pook &#8211; face aux Gorms, dans la for\u00eat de C\u0153ur Sombre et dans les interludes, le barbe et son jeune apprenti, Rutsi. Nous avons h\u00e2te de voir confirmer nos soup\u00e7ons (ou pas) sur certains personnages. Arriveront-ils \u00e0 vaincre Scramashank?<\/em><\/p>\n<p><em><span style=\"text-decoration: underline;\">Des lectures adulte<\/span>:<\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><em>(Romance historique) <strong><span style=\"text-decoration: underline;\">Le Clan MacPherson, La Rose du Highlander<\/span><\/strong> de Liv Fox <strong>(T4)<\/strong><\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-Rose-du-Highlander-T4.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"39836\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2025\/06\/29\/point-lecture-hebdomadaire-2025-25\/screenshot-236\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-Rose-du-Highlander-T4.jpg?fit=750%2C1163&amp;ssl=1\" data-orig-size=\"750,1163\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-Rose-du-Highlander-T4.jpg?fit=660%2C1024&amp;ssl=1\" class=\"size-thumbnail wp-image-39836 alignright\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-Rose-du-Highlander-T4.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-Rose-du-Highlander-T4.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-Rose-du-Highlander-T4.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/La-Rose-du-Highlander-T4.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>J&rsquo;ai lu, en e-book, le tome 4 du <span style=\"text-decoration: underline;\">Clan MacPherson, La Rose du Highlander<\/span> de Liv Fox (\u00e9d. Auto\u00e9dition, avril 2025, 217 pages), une romance historique se d\u00e9roulant en 1318, en pleine guerre entre l&rsquo;Angleterre et l\u2019\u00c9cosse. Fait prisonnier lors de la d\u00e9faite de l&rsquo;Irlande, Niall MacPherson, dernier fils du clan MacPherson est fait prisonnier par les Anglais. Il arrive \u00e0 s&rsquo;\u00e9chapper en prenant en otage, Margaret de Bohun, une des nombreuses ni\u00e8ces du roi d\u2019Angleterre, son oncle lui ayant arrang\u00e9 un mariage avec un de ses alli\u00e9s, un vieil homme d\u00e9j\u00e0 veuf \u00e0 plusieurs reprises. Cette derni\u00e8re voit sa vie lui \u00e9chapper. Ils n&rsquo;auraient jamais d\u00fb se rencontrer et finir ensemble sur les routes d\u2019\u00c9cosse. Entre loyaut\u00e9 et passion, jusqu&rsquo;o\u00f9 sont-ils pr\u00eats \u00e0 aller?<\/em><\/p>\n<p style=\"text-align: justify;\"><em> J&rsquo;ai appr\u00e9ci\u00e9 l&rsquo;alchimie entre les deux personnages, Niall ayant consacr\u00e9 sa vie aux combats pour l&rsquo;ind\u00e9pendance de son pays, sous les ordres du roi d\u2019\u00c9cosse tout comme Margaret qui, bon gr\u00e9 mal gr\u00e9, a accept\u00e9 \u00e0 un mariage arrang\u00e9 pour son oncle et l&rsquo;Angleterre. Leur attirance r\u00e9ciproque va remettre en question leur choix de vie. Mais est-ce possible? En tant qu&rsquo;otage anglais, la jeune femme pourrait-elle sacrifier pour le bien du peuple \u00e9cossais? Et si le c\u0153ur du jeune homme en d\u00e9cidait autrement? <\/em><em>Au vu du tome pr\u00e9c\u00e9dent, je m&rsquo;attendais \u00e0 ce type de romance bas\u00e9e sur l&rsquo;opposition Anglaise\/Highlander, les pr\u00e9jug\u00e9s, les apparences trompeuses ou bien encore le choix entre devoir et amour. Elle m&rsquo;a bien plu. L&rsquo;intrigue est addictive, avec son lot de rebondissements, de proximit\u00e9 forc\u00e9e, d&rsquo;h\u00e9sitations l\u00e9gitimes et de suspense m\u00eame si bien s\u00fbr on sait comment tout cela va se terminer. Un bon voire tr\u00e8s bon moment de lecture avec cette romance qui cl\u00f4t cette saga, en tout cas du point de vue de la fratrie, l&rsquo;autrice ayant annonc\u00e9 un tome bonus avec le fr\u00e8re de la femme de l&rsquo;a\u00een\u00e9 MacPherson!<\/em><\/p>\n<ul>\n<li><em>(Novella SF) <strong><span style=\"text-decoration: underline;\">Hard Mary<\/span><\/strong> de Sofia Samatar<\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Hard-Mary.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"39865\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2025\/06\/29\/point-lecture-hebdomadaire-2025-25\/screenshot-238\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Hard-Mary.jpg?fit=750%2C1130&amp;ssl=1\" data-orig-size=\"750,1130\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Hard-Mary.jpg?fit=676%2C1018&amp;ssl=1\" class=\"alignleft size-thumbnail wp-image-39865\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Hard-Mary.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Hard-Mary.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Hard-Mary.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Hard-Mary.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><em>J&rsquo;ai lu, en e-book, <span style=\"text-decoration: underline;\">Hard Mary<\/span> de Sofia Samatar (\u00e9d. Argyl, avril 2015, 128 pages), une novella SF qui se d\u00e9roule dans un futur ind\u00e9termin\u00e9, \u00e0 Jericho, un village tr\u00e8s religieux de Pennsylvanie dans lequel, un groupe de jeunes femmes, \u00e0 peine sorties de l&rsquo;adolescence et en \u00e2ge d&rsquo;\u00eatre mari\u00e9es, d\u00e9couvrent, dans une grange, \u00e0 quelques jours de No\u00ebl, un robot fabriqu\u00e9 par Profane Industries dont il ne reste qu&rsquo;un buste f\u00e9minin m\u00e9tallique qu&rsquo;elle baptise Hard Mary. Arriveront-elles \u00e0 garder secr\u00e8te leur d\u00e9couverte? Au vu du synopsis, je m&rsquo;attendais \u00e0 une autre histoire, \u00e0 tout le moins, avoir le point de vue du robot f\u00e9minin. Mais les questionnements sont surtout ceux d&rsquo;une des jeunes femmes \u00e0 travers son journal intime qui revient sur ce qui s&rsquo;est pass\u00e9, le soir de leur rencontre avec Hard Mary. Une lecture sur notamment le libre-arbitre, le poids de la religion, la condition de la femme, le rapport aux technologies avec une fin ouverte!<\/em><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Ma lecture en cours<\/span>:<\/strong><\/p>\n<p><em>(Roman contemporain) <strong><span style=\"text-decoration: underline;\">Le restaurant des recettes oubli\u00e9es<\/span><\/strong> de Hisashi Kashiwai<\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Le-restaurant-des-recettes-oubliees.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"39864\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2025\/06\/29\/point-lecture-hebdomadaire-2025-25\/screenshot-237\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Le-restaurant-des-recettes-oubliees.jpg?fit=750%2C1024&amp;ssl=1\" data-orig-size=\"750,1024\" data-comments-opened=\"1\" data-image-title=\"\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Le-restaurant-des-recettes-oubliees.jpg?fit=676%2C923&amp;ssl=1\" class=\"size-thumbnail wp-image-39864 alignright\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Le-restaurant-des-recettes-oubliees.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Le-restaurant-des-recettes-oubliees.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Le-restaurant-des-recettes-oubliees.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Le-restaurant-des-recettes-oubliees.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><em>J&rsquo;ai lu, en e-book, la premi\u00e8re partie et le premier chapitre de la seconde (65 pages) du <span style=\"text-decoration: underline;\">Restaurant des recettes oubli\u00e9es<\/span> de Hisashi Kashiwai (\u00e9d. Nami, avril 2023, 256 pages), un roman contemporain tr\u00e8s gourmand et paru pour la premi\u00e8re fois au Japon en 2013. Ce roman avait \u00e9t\u00e9 propos\u00e9 par Hilde et Lou comme lecture commune et facultative en avril dernier dans le cadre de leur challenge Un mois au Japon 2025. En d\u00e9butant le chapitre 2, je me suis aper\u00e7ue que la structure narrative d&rsquo;un chapitre \u00e0 l&rsquo;autre est similaire et j&rsquo;ai pr\u00e9f\u00e9r\u00e9 mettre en pause ma lecture comme si chaque chapitre \u00e9tait une nouvelle plut\u00f4t qu&rsquo;un roman. Je reprendrai ma lecture la semaine prochaine, ne la lisant pas d&rsquo;une traite, ce qui est tr\u00e8s rare pour moi. On y fait connaissance avec Nagare Kamogawa et sa fille Koishi qui tiennent un restaurant discret \u00e0 Kyoto. En plus de savoureux repas faits maison, ils proposent aux clients qui arrivent \u00e0 trouver leur restaurant de cuisiner un plat qu&rsquo;ils ont marqu\u00e9 leur vie mais dont la recette est depuis longtemps oubli\u00e9e. Dans la premi\u00e8re partie intitul\u00e9 \u00ab\u00a0Les nabeyaki udon\u00a0\u00bb, un ancien coll\u00e8gue de Nagare, Hideji Kuboyama lui demande de retrouver la recette de sa femme d\u00e9c\u00e9d\u00e9e.\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"38247\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2025\/01\/27\/point-lecture-hebdomadaire-2025-4\/semaine-a-1000-du-pingoin-vert-dates-2025\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?fit=800%2C800&amp;ssl=1\" data-orig-size=\"800,800\" data-comments-opened=\"1\" data-image-title=\"Semaine \u00e0 1000 du Pingoin Vert &amp;#8211; dates 2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?fit=676%2C676&amp;ssl=1\" class=\"wp-image-38247 alignleft\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?resize=141%2C141\" alt=\"\" width=\"141\" height=\"141\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/01\/Semaine-a-1000-du-Pingoin-Vert-dates-2025.jpg?resize=676%2C676&amp;ssl=1 676w\" sizes=\"auto, (max-width: 141px) 100vw, 141px\" \/><\/a>Cette semaine c\u2019\u00e9tait une Semaine \u00e0 mille pages organis\u00e9e par <a href=\"https:\/\/www.instagram.com\/petit_pingouin_vert\/\">Le pingouin vert<\/a> sur IG chaque mois tout au long de l\u2019ann\u00e9e 2025. Alors combien ai-je lu de pages cette semaine? 410 pages lues sans compter les pages jeunesse lues avec mon mini lutin.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cette fin de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re qui ont \u00e9t\u00e9 peu nombreuses, compte-tenu de nos sorties du soir (plage, f\u00eate de la musique&#8230;) ou visionnages.\u00a0 Nos lectures du 16 au 22 juin 2025: Des lectures jeunesse: Nous avons [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":39924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2140,873,363],"tags":[4647,4565,1085,367,3311,4648,2767,3777,1643,4152,3209,905,789,3083,4646],"class_list":["post-39835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mini-blogueur","category-mini-challenger","category-mini-lecteur","tag-hisashi-kashiwai","tag-kieran-larwood","tag-lecture-adulte","tag-lecture-jeunesse","tag-liv-fox","tag-novella","tag-point-lecture-hebdo","tag-roman-contemporain","tag-roman-court","tag-roman-sf","tag-romance-historique","tag-romans-adulte","tag-romans-jeunesse","tag-semaine-a-mille-pages","tag-sofia-samatar","post-preview"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/06\/Point-lecture-hebdo-2025-25.jpg?fit=1983%2C1440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9zhGx-amv","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":39365,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2025\/05\/09\/point-lecture-hebdomadaire-2025-18\/","url_meta":{"origin":39835,"position":0},"title":"Point lecture hebdomadaire 2025 #18","author":"Jojo","date":"9 mai 2025","format":false,"excerpt":"En cette presque fin de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re. Nos lectures du 28 avril au 4 mai 2025: Des lectures jeunesse: Nous avons continu\u00e9 \u00e0 lire le tome 1 d'une trilogie fantasy : La\u2026","rel":"","context":"Dans &quot;Mini blogueur&quot;","block_context":{"text":"Mini blogueur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-blogueur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-18.jpg?fit=1200%2C975&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-18.jpg?fit=1200%2C975&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-18.jpg?fit=1200%2C975&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-18.jpg?fit=1200%2C975&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-18.jpg?fit=1200%2C975&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37057,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2024\/09\/30\/point-lecture-hebdomadaire-2024-39\/","url_meta":{"origin":39835,"position":1},"title":"Point lecture hebdomadaire 2024 #39","author":"Jojo","date":"30 septembre 2024","format":false,"excerpt":"En ce d\u00e9but de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re. Nos lectures du 23 au 29 septembre 2024: Des lectures jeunesse: Nous avons continu\u00e9 chaque soir et presque fini de lire Le jardin secret de Frances\u2026","rel":"","context":"Dans &quot;Mini blogueur&quot;","block_context":{"text":"Mini blogueur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-blogueur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/04\/Le-jardin-secret-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":39382,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2025\/05\/16\/point-lecture-hebdomadaire-2025-19\/","url_meta":{"origin":39835,"position":2},"title":"Point lecture hebdomadaire 2025 #19","author":"Jojo","date":"16 mai 2025","format":false,"excerpt":"En cette presque fin de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re. Nos lectures du 5 au 11 mai 2025: Des lectures jeunesse: Nous avons fini de lire le tome 1 d'une trilogie fantasy : La l\u00e9gende\u2026","rel":"","context":"Dans &quot;Mini blogueur&quot;","block_context":{"text":"Mini blogueur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-blogueur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-19.jpg?fit=1200%2C915&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-19.jpg?fit=1200%2C915&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-19.jpg?fit=1200%2C915&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-19.jpg?fit=1200%2C915&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-19.jpg?fit=1200%2C915&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":40060,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2025\/07\/14\/point-lecture-hebdomadaire-2025-28\/","url_meta":{"origin":39835,"position":3},"title":"Point lecture hebdomadaire 2025 #28","author":"Jojo","date":"14 juillet 2025","format":false,"excerpt":"En ce d\u00e9but de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re, ayant \u00e9galement regard\u00e9 la mini-s\u00e9rie en 3-D r\u00e9alis\u00e9e en 2025 par Alain Chabat, Ast\u00e9rix et Ob\u00e9lix, Le combat des Chefs.\u00a0 Nos lectures du 7 au 13\u2026","rel":"","context":"Dans &quot;Mini blogueur&quot;","block_context":{"text":"Mini blogueur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-blogueur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/07\/Point-lecture-hebdo-2025-28.jpg?fit=1200%2C905&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/07\/Point-lecture-hebdo-2025-28.jpg?fit=1200%2C905&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/07\/Point-lecture-hebdo-2025-28.jpg?fit=1200%2C905&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/07\/Point-lecture-hebdo-2025-28.jpg?fit=1200%2C905&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/07\/Point-lecture-hebdo-2025-28.jpg?fit=1200%2C905&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39430,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2025\/05\/26\/point-lecture-hebdomadaire-2025-21\/","url_meta":{"origin":39835,"position":4},"title":"Point lecture hebdomadaire 2025 #21","author":"Jojo","date":"26 mai 2025","format":false,"excerpt":"En ce d\u00e9but de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re, ayant \u00e9galement regard\u00e9 l'anime du Pavillon des hommes. Nos lectures du 19 au 25 mai 2025: Des lectures jeunesse: Nous avons continu\u00e9 de lire jusqu'au chapitre\u2026","rel":"","context":"Dans &quot;Mini blogueur&quot;","block_context":{"text":"Mini blogueur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-blogueur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-21.jpg?fit=1200%2C939&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-21.jpg?fit=1200%2C939&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-21.jpg?fit=1200%2C939&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-21.jpg?fit=1200%2C939&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/05\/Point-lecture-hebdo-2025-21.jpg?fit=1200%2C939&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":39012,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2025\/04\/23\/point-lecture-hebdomadaire-2025-16\/","url_meta":{"origin":39835,"position":5},"title":"Point lecture hebdomadaire 2025 #16","author":"Jojo","date":"23 avril 2025","format":false,"excerpt":"En ce milieu de semaine, voici mon point lecture hebdomadaire avec un retour sur nos lectures (mais pas nos relectures) de la semaine derni\u00e8re qui \u00e9tait \u00e0 la fois une semaine \u00e0 1000 pages du Pingouin Vert et un Week-end \u00e0 1000 du 18 au 20 avril 2025. Nos lectures\u2026","rel":"","context":"Dans &quot;Mini blogueur&quot;","block_context":{"text":"Mini blogueur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-blogueur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/04\/Point-lecture-hebdo-2025-16.jpg?fit=1200%2C893&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/04\/Point-lecture-hebdo-2025-16.jpg?fit=1200%2C893&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/04\/Point-lecture-hebdo-2025-16.jpg?fit=1200%2C893&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/04\/Point-lecture-hebdo-2025-16.jpg?fit=1200%2C893&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/04\/Point-lecture-hebdo-2025-16.jpg?fit=1200%2C893&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/39835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/comments?post=39835"}],"version-history":[{"count":14,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/39835\/revisions"}],"predecessor-version":[{"id":40105,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/39835\/revisions\/40105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media\/39924"}],"wp:attachment":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media?parent=39835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/categories?post=39835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/tags?post=39835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}