{"id":15550,"date":"2021-02-04T10:04:14","date_gmt":"2021-02-04T09:04:14","guid":{"rendered":"http:\/\/www.jojoenherbe.com\/?p=15550"},"modified":"2022-07-21T13:36:03","modified_gmt":"2022-07-21T11:36:03","slug":"au-fil-des-pages-avec-mariette-soupir-et-le-petit-cerisier","status":"publish","type":"post","link":"https:\/\/www.jojoenherbe.com\/index.php\/2021\/02\/04\/au-fil-des-pages-avec-mariette-soupir-et-le-petit-cerisier\/","title":{"rendered":"Au fil des pages avec Mariette, Soupir et le petit cerisier"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-2-scaled.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"15554\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2021\/02\/04\/au-fil-des-pages-avec-mariette-soupir-et-le-petit-cerisier\/mariette-soupir-et-le-petit-cerisier-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-2-scaled.jpg?fit=2560%2C1511&amp;ssl=1\" data-orig-size=\"2560,1511\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1611052863&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Mariette, Soupir et le petit cerisier 2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-2-scaled.jpg?fit=676%2C399&amp;ssl=1\" class=\"alignleft size-thumbnail wp-image-15554\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-2.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-2-scaled.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-2-scaled.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-2-scaled.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-3-scaled.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"15555\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2021\/02\/04\/au-fil-des-pages-avec-mariette-soupir-et-le-petit-cerisier\/mariette-soupir-et-le-petit-cerisier-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-3-scaled.jpg?fit=2560%2C1552&amp;ssl=1\" data-orig-size=\"2560,1552\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1611052797&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Mariette, Soupir et le petit cerisier 3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-3-scaled.jpg?fit=676%2C410&amp;ssl=1\" class=\"alignleft size-thumbnail wp-image-15555\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-3.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-3-scaled.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-3-scaled.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-3-scaled.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Nous empruntons \u00e0 la m\u00e9diath\u00e8que <span style=\"text-decoration: underline;\">Mariette, Soupir et le petit cerisier<\/span> d\u2019Ir\u00e8ne Schwartz et Fr\u00e9d\u00e9ric Stehr (\u00e9d. L\u2019\u00e9cole des loisirs, 2005), un album jeunesse \u00e0 partir de 3 ans. Un matin d&rsquo;\u00e9t\u00e9, Soupir et Mariette d\u00e9couvrent la neige qui est tomb\u00e9e dans la nuit. Elles s&rsquo;amusent avec cette dr\u00f4le de neige jusqu&rsquo;\u00e0 s&rsquo;\u00e9loigner un peu trop du terrier. <\/em><\/p>\n<p style=\"text-align: justify;\"><em><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-4-scaled.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"15556\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2021\/02\/04\/au-fil-des-pages-avec-mariette-soupir-et-le-petit-cerisier\/mariette-soupir-et-le-petit-cerisier-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-4-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1611052838&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Mariette, Soupir et le petit cerisier 4\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-4-scaled.jpg?fit=676%2C507&amp;ssl=1\" class=\"size-thumbnail wp-image-15556 alignright\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-4.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-4-scaled.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-4-scaled.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-4-scaled.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>L&rsquo;histoire est aussi mignonne que celle que nous avions d\u00e9j\u00e0 lu de cette famille de marmottes, <a href=\"http:\/\/www.jojoenherbe.com\/index.php\/2021\/01\/25\/au-fil-des-pages-avec-mariette-et-soupir-cherchent-une-maison\/\"><span style=\"text-decoration: underline;\">Mariette et Soupir cherchent une maison<\/span><\/a>. Par leur imprudence, les deux petites marmottes d\u00e9couvrent des fruits d\u00e9licieux, des cerises. Mais comment leur m\u00e8re pouvait elle aussi les conna\u00eetre? Un tr\u00e8s bon moment de lecture avec cet album jeunesse rigolo et gourmand pour les amateurs de neige et de cerises! Il peut \u00eatre aussi bien lu en hiver qu&rsquo;en \u00e9t\u00e9 pour une \u00e9chapp\u00e9e montagnarde.<\/em><\/p>\n<div style=\"width: 124px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/lh3.googleusercontent.com\/pw\/ACtC-3eIuIHfDCWnQjrbP_Gttnq9qrZJ0sCLWnTR3GjIOIiC54aYp8f1rKz8fy3EJIYJcUrzUv3KnF-YnYTE-vhMmRU8myeq_V_5OYKPelcJ6I4-bD-P1SjmJYevXt0TGhPCpROfcXeg5SJ_4KvwWeBQfvsOWw=w285-h217-no?authuser=1\" alt=\"\" width=\"114\" height=\"87\" \/><p class=\"wp-caption-text\">Challenge Petit Bac d&rsquo;<a href=\"https:\/\/ennalit.wordpress.com\/2020\/12\/01\/challenge-petit-bac-2021-qui-veut-jouer\/\">Enna<\/a> #3 Cat\u00e9gorie Adjectif: \u00ab\u00a0Petit\u00a0\u00bb<\/p><\/div>\n<div style=\"width: 125px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"nonealign widthoriginal\" src=\"https:\/\/i0.wp.com\/p4.storage.canalblog.com\/40\/68\/1394281\/128273873.png?resize=115%2C83&#038;ssl=1\" alt=\"\" width=\"115\" height=\"83\" border=\"0\" \/><p class=\"wp-caption-text\">Participation #15 Challenge Des livres (et des \u00e9crans) en cuisine de <a href=\"https:\/\/mapetitemediatheque.fr\/2020\/12\/des-livres-et-des-ecrans-en-cuisine-2021\/\">Bidib<\/a> et <a href=\"http:\/\/croquerlespages.canalblog.com\/archives\/2020\/12\/20\/38715076.html\">Fondant<\/a> #Cerise<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nous empruntons \u00e0 la m\u00e9diath\u00e8que Mariette, Soupir et le petit cerisier d\u2019Ir\u00e8ne Schwartz et Fr\u00e9d\u00e9ric Stehr (\u00e9d. L\u2019\u00e9cole des loisirs, 2005), un album jeunesse \u00e0 partir de 3 ans. Un matin d&rsquo;\u00e9t\u00e9, Soupir et Mariette d\u00e9couvrent la neige qui est tomb\u00e9e dans la nuit. Elles s&rsquo;amusent avec cette dr\u00f4le de neige jusqu&rsquo;\u00e0 s&rsquo;\u00e9loigner un peu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[363],"tags":[785,409,2150,2018,2019,611,2047,2048,367,1857,1155,369],"class_list":["post-15550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mini-lecteur","tag-3-6-ans","tag-albums-jeunesse","tag-cerisier","tag-challenge-petit-bac-2021","tag-des-livres-et-des-ecrans-en-cuisine-2021","tag-ete","tag-frederic-stehr","tag-irene-schwartz","tag-lecture-jeunesse","tag-marmotte","tag-montagne","tag-neige","post-preview"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/02\/Mariette-Soupir-et-le-petit-cerisier-scaled.jpg?fit=2560%2C1818&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9zhGx-42O","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":15344,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2021\/01\/25\/au-fil-des-pages-avec-mariette-et-soupir-cherchent-une-maison\/","url_meta":{"origin":15550,"position":0},"title":"Au fil des pages avec Mariette et Soupir cherchent une maison","author":"Jojo","date":"25 janvier 2021","format":false,"excerpt":"Comme l'\u00e9t\u00e9 dernier, nous empruntons \u00e0 la m\u00e9diath\u00e8que Mariette et Soupir cherchent une maison d\u2019Ir\u00e8ne Schwartz et Fr\u00e9d\u00e9ric Stehr (\u00e9d. L\u2019\u00e9cole des loisirs, 1996), un album jeunesse \u00e0 partir de 3 ans. Par une belle journ\u00e9e ensoleill\u00e9e, la famille de marmottes se r\u00e9veille quand soudain, Soupir d\u00e9couvre une dr\u00f4le de\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Mariette-et-Soupir-cherchent-une-maison-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Mariette-et-Soupir-cherchent-une-maison-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Mariette-et-Soupir-cherchent-une-maison-scaled.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Mariette-et-Soupir-cherchent-une-maison-scaled.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Mariette-et-Soupir-cherchent-une-maison-scaled.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14537,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2020\/12\/27\/deuxieme-alphabet-des-animaux-m-comme-marmotte\/","url_meta":{"origin":15550,"position":1},"title":"Deuxi\u00e8me alphabet des animaux: M comme Marmotte","author":"Jojo","date":"27 d\u00e9cembre 2020","format":false,"excerpt":"Pour la semaine 37 de mon challenge sur Instagram #jojoenherbeetcieillustre qui associe la premi\u00e8re lettre d'un animal avec une illustration tir\u00e9e de la litt\u00e9rature jeunesse en suivant l'ordre de l'alphabet, il s'agit du M comme Marmotte. Alors voici notre s\u00e9lection de marmottes qui sera mise \u00e0 jour au fur-et-\u00e0-mesure de\u2026","rel":"","context":"Dans &quot;Mini challenger&quot;","block_context":{"text":"Mini challenger","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-challenger\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/12\/Selection-de-marmottes-scaled.jpg?fit=1200%2C814&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/12\/Selection-de-marmottes-scaled.jpg?fit=1200%2C814&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/12\/Selection-de-marmottes-scaled.jpg?fit=1200%2C814&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/12\/Selection-de-marmottes-scaled.jpg?fit=1200%2C814&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/12\/Selection-de-marmottes-scaled.jpg?fit=1200%2C814&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24831,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2022\/04\/13\/au-fil-des-pages-avec-la-neige-en-ete\/","url_meta":{"origin":15550,"position":2},"title":"Au fil des pages avec La neige en \u00e9t\u00e9","author":"Jojo","date":"13 avril 2022","format":false,"excerpt":"Lors d'Un Mois au Japon 2021, j'avais lu mais pas chroniqu\u00e9 La neige en \u00e9t\u00e9 de R\u00e9gine Jos\u00e9phine et Bing Liu (\u00e9d. Anna Chanel, 2010), un album jeunesse \u00e0 partir de 6 ans pensant que l'histoire se d\u00e9roulait au Japon. Dans des temps anciens, en Chine, un cerisier est si\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2022\/04\/La-neige-en-ete-scaled.jpg?fit=1200%2C873&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2022\/04\/La-neige-en-ete-scaled.jpg?fit=1200%2C873&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2022\/04\/La-neige-en-ete-scaled.jpg?fit=1200%2C873&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2022\/04\/La-neige-en-ete-scaled.jpg?fit=1200%2C873&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2022\/04\/La-neige-en-ete-scaled.jpg?fit=1200%2C873&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":29903,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2023\/02\/18\/au-fil-des-pages-avec-il-neige\/","url_meta":{"origin":15550,"position":3},"title":"Au fil des pages avec Il neige!","author":"Jojo","date":"18 f\u00e9vrier 2023","format":false,"excerpt":"Nous avons lu Il neige! de Hyejin Go (\u00e9d. Picquier Jeunesse, 2018), un album jeunesse \u00e0 partir de 3 ans et qui a fait partie de la s\u00e9lection Maternelle du 32\u00e8me Prix des Incos 2021. M\u00e9content d'avoir \u00e9t\u00e9 r\u00e9veill\u00e9 alors qu\u2019il est en train d\u2019hiberner, un ours d\u00e9couvre avec ravissement\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/04\/Il-neige-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/04\/Il-neige-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/04\/Il-neige-scaled.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/04\/Il-neige-scaled.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/04\/Il-neige-scaled.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15016,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2021\/08\/03\/recap-du-challenge-petit-bac-2021\/","url_meta":{"origin":15550,"position":4},"title":"R\u00e9cap&rsquo; du Challenge Petit Bac 2021","author":"Jojo","date":"3 ao\u00fbt 2021","format":false,"excerpt":"Cette ann\u00e9e 2021, je participe pour la troisi\u00e8me fois cons\u00e9cutive au Challenge Petit Bac d'Enna, les cinq premi\u00e8res cat\u00e9gories restant identiques aux ann\u00e9es pr\u00e9c\u00e9dentes. En ce d\u00e9but d'ao\u00fbt, j'avais envie de faire un petit point sur mes participations au challenge, ayant fini ma 10e ligne et commenc\u00e9 la 11e. Voici\u2026","rel":"","context":"Dans &quot;Mini challenger&quot;","block_context":{"text":"Mini challenger","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-challenger\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/08\/Challenge-Petit-Bac-2021-scaled.jpg?fit=1200%2C962&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/08\/Challenge-Petit-Bac-2021-scaled.jpg?fit=1200%2C962&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/08\/Challenge-Petit-Bac-2021-scaled.jpg?fit=1200%2C962&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/08\/Challenge-Petit-Bac-2021-scaled.jpg?fit=1200%2C962&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/08\/Challenge-Petit-Bac-2021-scaled.jpg?fit=1200%2C962&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14897,"url":"https:\/\/www.jojoenherbe.com\/index.php\/2021\/01\/07\/nos-lectures-hivernales-2021\/","url_meta":{"origin":15550,"position":5},"title":"Nos lectures hivernales 2021","author":"Jojo","date":"7 janvier 2021","format":false,"excerpt":"Comme je l'avais fait pour l'automne dernier, je souhaite \u00e9galement regrouper sous un m\u00eame billet nos lectures hivernales commenc\u00e9es en d\u00e9cembre 2020. Ce billet sera ainsi actualis\u00e9 tout au long de cet hiver au gr\u00e9 de nos lectures sur ce th\u00e8me. Je ne reprends toutefois pas nos relectures de livres\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"https:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Selection-Hiver-scaled.jpg?fit=1200%2C765&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Selection-Hiver-scaled.jpg?fit=1200%2C765&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Selection-Hiver-scaled.jpg?fit=1200%2C765&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Selection-Hiver-scaled.jpg?fit=1200%2C765&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/01\/Selection-Hiver-scaled.jpg?fit=1200%2C765&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/15550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/comments?post=15550"}],"version-history":[{"count":1,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/15550\/revisions"}],"predecessor-version":[{"id":26624,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/15550\/revisions\/26624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media\/15557"}],"wp:attachment":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media?parent=15550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/categories?post=15550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/tags?post=15550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}