{"id":41695,"date":"2025-12-12T17:39:41","date_gmt":"2025-12-12T16:39:41","guid":{"rendered":"http:\/\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2.jpg"},"modified":"2025-12-12T17:39:41","modified_gmt":"2025-12-12T16:39:41","slug":"pal-rat-de-noel-2025-2","status":"inherit","type":"attachment","link":"https:\/\/www.jojoenherbe.com\/index.php\/2025\/12\/12\/rat-de-noel-2025\/pal-rat-de-noel-2025-2\/","title":{"rendered":"PAL RAT de No\u00ebl 2025 (2)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-41695","attachment","type-attachment","status-inherit","hentry","post-preview"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a9zhGx-aQv","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"231\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=300%2C231&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?resize=300%2C231&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?resize=1024%2C787&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?resize=768%2C590&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?resize=1536%2C1181&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?resize=2048%2C1574&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?resize=676%2C520&amp;ssl=1 676w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?w=1352 1352w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"41695\" data-permalink=\"https:\/\/www.jojoenherbe.com\/index.php\/2025\/12\/12\/rat-de-noel-2025\/pal-rat-de-noel-2025-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=2560%2C1968&amp;ssl=1\" data-orig-size=\"2560,1968\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone SE (3rd generation)&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1765557910&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"PAL RAT de No\u00ebl 2025 (2)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=676%2C520&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1968,"file":"2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg","filesize":1019489,"sizes":{"medium":{"file":"PAL-RAT-de-Noel-2025-2-300x231.jpg","width":300,"height":231,"filesize":37266,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=300%2C231&ssl=1"},"large":{"file":"PAL-RAT-de-Noel-2025-2-1024x787.jpg","width":1024,"height":787,"filesize":244316,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=676%2C520&ssl=1"},"thumbnail":{"file":"PAL-RAT-de-Noel-2025-2-150x150.jpg","width":150,"height":150,"filesize":20495,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"PAL-RAT-de-Noel-2025-2-768x590.jpg","width":768,"height":590,"filesize":153631,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=676%2C519&ssl=1"},"1536x1536":{"file":"PAL-RAT-de-Noel-2025-2-1536x1181.jpg","width":1536,"height":1181,"filesize":456632,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=1536%2C1181&ssl=1"},"2048x2048":{"file":"PAL-RAT-de-Noel-2025-2-2048x1574.jpg","width":2048,"height":1574,"filesize":715683,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=2048%2C1574&ssl=1"},"post-image":{"file":"PAL-RAT-de-Noel-2025-2-676x520.jpg","width":676,"height":520,"filesize":126117,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=676%2C520&ssl=1"},"full":{"file":"PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=2560%2C1968&ssl=1","width":2560,"height":1968,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg?fit=2560%2C1968&ssl=1"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone SE (3rd generation)","caption":"","created_timestamp":"1765557910","copyright":"","focal_length":"3.99","iso":"640","shutter_speed":"0.058823529411765","title":"","orientation":"1","keywords":[]},"original_image":"PAL-RAT-de-Noel-2025-2.jpg"},"post":41691,"source_url":"https:\/\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/12\/PAL-RAT-de-Noel-2025-2-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media\/41695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/comments?post=41695"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":41691,"href":"https:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/41691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}