{"id":11997,"date":"2020-08-29T21:54:26","date_gmt":"2020-08-29T19:54:26","guid":{"rendered":"http:\/\/www.jojoenherbe.com\/?p=11997"},"modified":"2021-06-21T12:51:02","modified_gmt":"2021-06-21T10:51:02","slug":"au-fil-des-pages-avec-splat-le-chat","status":"publish","type":"post","link":"http:\/\/www.jojoenherbe.com\/index.php\/2020\/08\/29\/au-fil-des-pages-avec-splat-le-chat\/","title":{"rendered":"Au fil des pages avec Splat le chat"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-2-scaled.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"12005\" data-permalink=\"http:\/\/www.jojoenherbe.com\/index.php\/2020\/08\/29\/au-fil-des-pages-avec-splat-le-chat\/splat-le-chat-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-2-scaled.jpg?fit=2560%2C1920\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1597242170&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Splat le chat 2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-2-scaled.jpg?fit=676%2C507\" class=\"alignleft wp-image-12005 size-thumbnail\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-2.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-2-scaled.jpg?resize=150%2C150 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-2-scaled.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-2-scaled.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-3-scaled.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"12006\" data-permalink=\"http:\/\/www.jojoenherbe.com\/index.php\/2020\/08\/29\/au-fil-des-pages-avec-splat-le-chat\/splat-le-chat-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-3-scaled.jpg?fit=2560%2C1920\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 7&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1597242186&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.090909090909091&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Splat le chat 3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-3-scaled.jpg?fit=676%2C507\" class=\"alignleft size-thumbnail wp-image-12006\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-3.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-3-scaled.jpg?resize=150%2C150 150w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-3-scaled.jpg?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-3-scaled.jpg?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><em>Nous empruntons \u00e0 la m\u00e9diath\u00e8que <span style=\"text-decoration: underline;\">Splat le chat<\/span> de Rob Scotton (\u00e9d. Nathan, 2011), un album jeunesse \u00e0 partir de 4 ans et qui a fait partie de la s\u00e9lection Maternelle du 22\u00e8me Prix des Incos en 2011. Splat va vivre sa premi\u00e8re journ\u00e9e \u00e0 l&rsquo;\u00e9cole des chats. Heureusement, il peut compter sur son ami Harry Souris pour rendre cette journ\u00e9e incroyable et surmonter sa peur d&rsquo;aller \u00e0 l&rsquo;\u00e9cole. Un bon moment de lecture avec cet album jeunesse rigolo qui permet de d\u00e9dramatiser une premi\u00e8re rentr\u00e9e des classes!<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Pour prolonger la lecture, nous faisons quelques activit\u00e9s comme celles trouv\u00e9es sur le blog de <a href=\"http:\/\/www.enmaternelle.fr\/2020\/07\/12\/splat-le-chat-tableaux-a-double-entree\/\">MC en maternelle<\/a> comme des tableaux \u00e0 double entr\u00e9e. N&rsquo;h\u00e9sitez pas \u00e0 aller faire un tour sur son blog pour voir toutes les activit\u00e9s qu&rsquo;elle propose.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous empruntons \u00e0 la m\u00e9diath\u00e8que Splat le chat de Rob Scotton (\u00e9d. Nathan, 2011), un album jeunesse \u00e0 partir de 4 ans et qui a fait partie de la s\u00e9lection Maternelle du 22\u00e8me Prix des Incos en 2011. Splat va vivre sa premi\u00e8re journ\u00e9e \u00e0 l&rsquo;\u00e9cole des chats. Heureusement, il peut compter sur son ami [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[363],"tags":[1031,409,386,705,740,749,538,367,555,1673,2628,605,1122,495,1420],"class_list":["post-11997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mini-lecteur","tag-4-7-ans","tag-albums-jeunesse","tag-amitie","tag-chat","tag-ecole","tag-exploitation-pedagogique","tag-humour","tag-lecture-jeunesse","tag-peur","tag-prix-des-incos","tag-prix-des-incos-2011","tag-rentree-scolaire","tag-rob-scotton","tag-souris","tag-splat","post-preview"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Splat-le-chat-scaled.jpg?fit=2560%2C1920","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9zhGx-37v","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":11740,"url":"http:\/\/www.jojoenherbe.com\/index.php\/2020\/08\/06\/au-fil-des-pages-avec-plouf-splat\/","url_meta":{"origin":11997,"position":0},"title":"Au fil des pages avec Plouf, Splat!","author":"Jojo","date":"6 ao\u00fbt 2020","format":false,"excerpt":"Un peu de fra\u00eecheur avec une lecture du moment! Nous avons emprunt\u00e9 \u00e0 la m\u00e9diath\u00e8que Plouf, Splat! de Rob Scotton (\u00e9d. Nathan, 2011), un album jeunesse \u00e0 partir de 4 ans et m\u00eame avant. D\u00e8s le r\u00e9veil, la journ\u00e9e de Splat s\u2019annonce mauvaise... Entre son copain de classe, Grouff qui\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"http:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Plouf-Splat-scaled.jpg?fit=1200%2C900&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Plouf-Splat-scaled.jpg?fit=1200%2C900&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Plouf-Splat-scaled.jpg?fit=1200%2C900&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Plouf-Splat-scaled.jpg?fit=1200%2C900&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/08\/Plouf-Splat-scaled.jpg?fit=1200%2C900&resize=1050%2C600 3x"},"classes":[]},{"id":10674,"url":"http:\/\/www.jojoenherbe.com\/index.php\/2020\/04\/10\/au-fil-des-pages-avec-splat-adore-jardiner\/","url_meta":{"origin":11997,"position":1},"title":"Au fil des pages avec Splat adore jardiner!","author":"Jojo","date":"10 avril 2020","format":false,"excerpt":"Nous lisons Splat adore jardiner! de Rob Scotton (\u00e9d. Nathan, 2015), un album jeunesse \u00e0 partir de 3 ans. Un jour de pluie proche du printemps, Harry Souris redonne le sourire \u00e0 Splat lorsqu'il trouve une graine. Ni l'un ni l'autre ne sachant jardiner, ils se rendent \u00e0 la biblioth\u00e8que\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"http:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/04\/Splat-adore-jardiner-scaled.jpg?fit=1200%2C860&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/04\/Splat-adore-jardiner-scaled.jpg?fit=1200%2C860&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/04\/Splat-adore-jardiner-scaled.jpg?fit=1200%2C860&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/04\/Splat-adore-jardiner-scaled.jpg?fit=1200%2C860&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/04\/Splat-adore-jardiner-scaled.jpg?fit=1200%2C860&resize=1050%2C600 3x"},"classes":[]},{"id":9348,"url":"http:\/\/www.jojoenherbe.com\/index.php\/2020\/01\/03\/au-fil-des-pages-avec-joyeux-noel-splat\/","url_meta":{"origin":11997,"position":2},"title":"Au fil des pages avec Joyeux No\u00ebl, Splat!","author":"Jojo","date":"3 janvier 2020","format":false,"excerpt":"Nous lisons et relisons Joyeux No\u00ebl, Splat! de Rob Scotton (\u00e9d. Nathan, 2012), un album jeunesse \u00e0 partir de 3 ans. Apr\u00e8s Halloween, nous retrouvons Splat le chat et Harry Souris dans les derniers pr\u00e9paratifs avant No\u00ebl: la lettre au P\u00e8re No\u00ebl, le sapin de No\u00ebl et le repas du\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"http:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/01\/Joyeux-Noel-Splat-scaled.jpg?fit=1200%2C900&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/01\/Joyeux-Noel-Splat-scaled.jpg?fit=1200%2C900&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/01\/Joyeux-Noel-Splat-scaled.jpg?fit=1200%2C900&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/01\/Joyeux-Noel-Splat-scaled.jpg?fit=1200%2C900&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/01\/Joyeux-Noel-Splat-scaled.jpg?fit=1200%2C900&resize=1050%2C600 3x"},"classes":[]},{"id":8463,"url":"http:\/\/www.jojoenherbe.com\/index.php\/2019\/11\/16\/au-fil-des-pages-avec-splat-a-la-chasse-aux-citrouilles\/","url_meta":{"origin":11997,"position":3},"title":"Au fil des pages avec Splat \u00e0 la chasse aux citrouilles","author":"Jojo","date":"16 novembre 2019","format":false,"excerpt":"Nous lisons et relisons depuis plusieurs jours Splat \u00e0 la chasse aux citrouilles de Rob Scotton (\u00e9d. Nathan, 2019), un album jeunesse \u00e0 partir de 3 ans. Accompagn\u00e9 de Harry la souris, Splat le chat s'est vu confier une mission d'une grande importance par sa m\u00e8re: aller r\u00e9cup\u00e9rer une citrouille\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"http:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2019\/11\/Splat-a-la-chasse-aux-citrouilles-scaled.jpg?fit=1200%2C900&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2019\/11\/Splat-a-la-chasse-aux-citrouilles-scaled.jpg?fit=1200%2C900&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2019\/11\/Splat-a-la-chasse-aux-citrouilles-scaled.jpg?fit=1200%2C900&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2019\/11\/Splat-a-la-chasse-aux-citrouilles-scaled.jpg?fit=1200%2C900&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2019\/11\/Splat-a-la-chasse-aux-citrouilles-scaled.jpg?fit=1200%2C900&resize=1050%2C600 3x"},"classes":[]},{"id":16519,"url":"http:\/\/www.jojoenherbe.com\/index.php\/2021\/03\/14\/troisieme-alphabet-des-animaux-c-comme-chat\/","url_meta":{"origin":11997,"position":4},"title":"Troisi\u00e8me alphabet des animaux: C comme Chat","author":"Jojo","date":"14 mars 2021","format":false,"excerpt":"Pour la semaine 48 de mon challenge de l'alphabet des animaux illustr\u00e9s sur Instagram #jojoenherbeetcieillustre qui associe la premi\u00e8re lettre d'un animal avec une illustration tir\u00e9e de la litt\u00e9rature jeunesse en suivant l'ordre de l'alphabet, il s'agit du C comme Chat. Alors voici notre s\u00e9lection de chats qui sera mise\u2026","rel":"","context":"Dans &quot;Mini challenger&quot;","block_context":{"text":"Mini challenger","link":"http:\/\/www.jojoenherbe.com\/index.php\/category\/mini-challenger\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/03\/Selection-Chats-scaled.jpg?fit=1200%2C737&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/03\/Selection-Chats-scaled.jpg?fit=1200%2C737&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/03\/Selection-Chats-scaled.jpg?fit=1200%2C737&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/03\/Selection-Chats-scaled.jpg?fit=1200%2C737&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2021\/03\/Selection-Chats-scaled.jpg?fit=1200%2C737&resize=1050%2C600 3x"},"classes":[]},{"id":13580,"url":"http:\/\/www.jojoenherbe.com\/index.php\/2020\/11\/03\/nos-lectures-automnales-2020\/","url_meta":{"origin":11997,"position":5},"title":"Nos lectures automnales 2020","author":"Jojo","date":"3 novembre 2020","format":false,"excerpt":"En ce d\u00e9but du mois de novembre 2020, nous continuons nos lectures automnales, \u00e0 d\u00e9faut de pouvoir nous promener dans les parcs, jardins ou for\u00eats - second confinement oblige - et apr\u00e8s avoir pass\u00e9 un joli mois d'octobre halloweenesque. Ce sont pour la plupart des relectures des ann\u00e9es pr\u00e9c\u00e9dentes et\u2026","rel":"","context":"Dans &quot;Mini lecteur&quot;","block_context":{"text":"Mini lecteur","link":"http:\/\/www.jojoenherbe.com\/index.php\/category\/mini-lecteur\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/11\/Lectures-automnales-scaled.jpg?fit=1200%2C881&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/11\/Lectures-automnales-scaled.jpg?fit=1200%2C881&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/11\/Lectures-automnales-scaled.jpg?fit=1200%2C881&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/11\/Lectures-automnales-scaled.jpg?fit=1200%2C881&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2020\/11\/Lectures-automnales-scaled.jpg?fit=1200%2C881&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/11997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/comments?post=11997"}],"version-history":[{"count":0,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/11997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media\/12007"}],"wp:attachment":[{"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media?parent=11997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/categories?post=11997"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/tags?post=11997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}