{"id":40410,"date":"2025-08-13T17:44:56","date_gmt":"2025-08-13T15:44:56","guid":{"rendered":"http:\/\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8.jpg"},"modified":"2025-08-13T17:44:56","modified_gmt":"2025-08-13T15:44:56","slug":"grottes-du-regulus-8","status":"inherit","type":"attachment","link":"http:\/\/www.jojoenherbe.com\/index.php\/2025\/08\/13\/le-temps-dune-visite-des-grottes-du-regulus\/grottes-du-regulus-8\/","title":{"rendered":"Grottes du R\u00e9gulus 8"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-40410","attachment","type-attachment","status-inherit","hentry","post-preview"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a9zhGx-avM","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=225%2C300\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?w=1920 1920w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?resize=225%2C300 225w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?resize=768%2C1024 768w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?resize=1152%2C1536 1152w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?resize=1536%2C2048 1536w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?resize=676%2C901 676w, https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?w=1352 1352w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" data-attachment-id=\"40410\" data-permalink=\"http:\/\/www.jojoenherbe.com\/index.php\/2025\/08\/13\/le-temps-dune-visite-des-grottes-du-regulus\/grottes-du-regulus-8\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=1920%2C2560\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-title=\"Grottes du R\u00e9gulus 8\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=676%2C901\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":2560,"file":"2025\/08\/Grottes-du-Regulus-8-scaled.jpg","filesize":1015052,"sizes":{"medium":{"file":"Grottes-du-Regulus-8-225x300.jpg","width":225,"height":300,"filesize":31541,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=225%2C300"},"large":{"file":"Grottes-du-Regulus-8-768x1024.jpg","width":768,"height":1024,"filesize":220047,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=676%2C901"},"thumbnail":{"file":"Grottes-du-Regulus-8-150x150.jpg","width":150,"height":150,"filesize":17733,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?resize=150%2C150"},"medium_large":{"file":"Grottes-du-Regulus-8-768x1024.jpg","width":768,"height":1024,"filesize":220047,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=676%2C901"},"1536x1536":{"file":"Grottes-du-Regulus-8-1152x1536.jpg","width":1152,"height":1536,"filesize":437134,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=1152%2C1536"},"2048x2048":{"file":"Grottes-du-Regulus-8-1536x2048.jpg","width":1536,"height":2048,"filesize":705536,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=1536%2C2048"},"post-image":{"file":"Grottes-du-Regulus-8-676x901.jpg","width":676,"height":901,"filesize":178184,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=676%2C901"},"full":{"file":"Grottes-du-Regulus-8-scaled.jpg?fit=1920%2C2560","width":1920,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg?fit=1920%2C2560"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone 7","caption":"","created_timestamp":"1752673946","copyright":"","focal_length":"3.99","iso":"32","shutter_speed":"0.04","title":"","orientation":"1","keywords":[]},"original_image":"Grottes-du-Regulus-8.jpg"},"post":40392,"source_url":"http:\/\/www.jojoenherbe.com\/wp-content\/uploads\/2025\/08\/Grottes-du-Regulus-8-scaled.jpg","_links":{"self":[{"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media\/40410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/comments?post=40410"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":40392,"href":"http:\/\/www.jojoenherbe.com\/index.php\/wp-json\/wp\/v2\/posts\/40392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}